{"id":138029,"date":"2023-03-05T08:03:11","date_gmt":"2023-03-05T08:03:11","guid":{"rendered":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/"},"modified":"2023-03-05T08:03:11","modified_gmt":"2023-03-05T08:03:11","slug":"emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games","status":"publish","type":"post","link":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/","title":{"rendered":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition &#8211; Big Fish Games"},"content":{"rendered":"<p>Mahjong &amp;middot; Brain Teaser &amp;middot; iPad &amp;amp; iPhone Games &amp;middot; Android Games Home &amp;middot; New Releases Android Games &amp;middot; Search&amp;nbsp;&#8230;<br \/><a href=\"https:\/\/www.bigfishgames.com\/us\/en\/games\/15950\/emergency-crew-3-perfect-getaway-ce\/?pc&amp;lang=en\" target=\"_blank\" title=\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games\" rel=\"noopener\">View full source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mahjong &amp;middot; Brain Teaser &amp;middot; iPad &amp;amp; iPhone Games &amp;middot; Android Games Home &amp;middot; New [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":43748,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7026],"class_list":["post-138029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-big-fish-games"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News<\/title>\n<meta name=\"description\" content=\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News\" \/>\n<meta property=\"og:description\" content=\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/\" \/>\n<meta property=\"og:site_name\" content=\"iPhone News\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-05T08:03:11+00:00\" \/>\n<meta name=\"author\" content=\"iPhone News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"iPhone News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/\"},\"author\":{\"name\":\"iPhone News\",\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/caf8b2b53992652ab52c63895f2f655d\"},\"headline\":\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition &#8211; Big Fish Games\",\"datePublished\":\"2023-03-05T08:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/\"},\"wordCount\":42,\"publisher\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/caf8b2b53992652ab52c63895f2f655d\"},\"image\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-112.jpg\",\"keywords\":[\"Big Fish Games\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/\",\"url\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/\",\"name\":\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-112.jpg\",\"datePublished\":\"2023-03-05T08:03:11+00:00\",\"description\":\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-112.jpg\",\"contentUrl\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/wp-content\\\/uploads\\\/temp-112.jpg\",\"width\":2048,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/2023\\\/03\\\/05\\\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition &#8211; Big Fish Games\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/\",\"name\":\"iPhone News\",\"description\":\"Daily news about iPhone - fresh news, every day\",\"publisher\":{\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/caf8b2b53992652ab52c63895f2f655d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/iphone.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/caf8b2b53992652ab52c63895f2f655d\",\"name\":\"iPhone News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g\",\"caption\":\"iPhone News\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/iphone.4800bps.com\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News","description":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/","og_locale":"en_US","og_type":"article","og_title":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News","og_description":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News","og_url":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/","og_site_name":"iPhone News","article_published_time":"2023-03-05T08:03:11+00:00","author":"iPhone News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"iPhone News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/#article","isPartOf":{"@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/"},"author":{"name":"iPhone News","@id":"https:\/\/iphone.4800bps.com\/blog\/#\/schema\/person\/caf8b2b53992652ab52c63895f2f655d"},"headline":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition &#8211; Big Fish Games","datePublished":"2023-03-05T08:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/"},"wordCount":42,"publisher":{"@id":"https:\/\/iphone.4800bps.com\/blog\/#\/schema\/person\/caf8b2b53992652ab52c63895f2f655d"},"image":{"@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/#primaryimage"},"thumbnailUrl":"https:\/\/iphone.4800bps.com\/blog\/wp-content\/uploads\/temp-112.jpg","keywords":["Big Fish Games"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/","url":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/","name":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News","isPartOf":{"@id":"https:\/\/iphone.4800bps.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/#primaryimage"},"image":{"@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/#primaryimage"},"thumbnailUrl":"https:\/\/iphone.4800bps.com\/blog\/wp-content\/uploads\/temp-112.jpg","datePublished":"2023-03-05T08:03:11+00:00","description":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition - Big Fish Games - iPhone News","breadcrumb":{"@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/#primaryimage","url":"https:\/\/iphone.4800bps.com\/blog\/wp-content\/uploads\/temp-112.jpg","contentUrl":"https:\/\/iphone.4800bps.com\/blog\/wp-content\/uploads\/temp-112.jpg","width":2048,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/iphone.4800bps.com\/blog\/2023\/03\/05\/emergency-crew-3-perfect-getaway-collectors-edition-big-fish-games\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iphone.4800bps.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Emergency Crew 3: Perfect Getaway Collector&#039;s Edition &#8211; Big Fish Games"}]},{"@type":"WebSite","@id":"https:\/\/iphone.4800bps.com\/blog\/#website","url":"https:\/\/iphone.4800bps.com\/blog\/","name":"iPhone News","description":"Daily news about iPhone - fresh news, every day","publisher":{"@id":"https:\/\/iphone.4800bps.com\/blog\/#\/schema\/person\/caf8b2b53992652ab52c63895f2f655d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iphone.4800bps.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/iphone.4800bps.com\/blog\/#\/schema\/person\/caf8b2b53992652ab52c63895f2f655d","name":"iPhone News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g","caption":"iPhone News"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/b9698a8c370c831fd1e42560a54ea105f77602f27ef26674f9b47a27fed7974a?s=96&d=mm&r=g"},"sameAs":["http:\/\/iphone.4800bps.com\/blog\/"]}]}},"_links":{"self":[{"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/138029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/comments?post=138029"}],"version-history":[{"count":0,"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/138029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/media\/43748"}],"wp:attachment":[{"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/media?parent=138029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/categories?post=138029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iphone.4800bps.com\/blog\/wp-json\/wp\/v2\/tags?post=138029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}